{"id":9723,"date":"2021-08-24T10:19:10","date_gmt":"2021-08-24T08:19:10","guid":{"rendered":"https:\/\/ramarfp.com\/?p=9723"},"modified":"2021-08-24T10:23:30","modified_gmt":"2021-08-24T08:23:30","slug":"ramar-fp","status":"publish","type":"post","link":"https:\/\/ramarfp.com\/ca\/ramar-fp\/","title":{"rendered":"Tot el que has de con\u00e8ixer de RAMAR FP!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9723\" class=\"elementor elementor-9723\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-433397b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"433397b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e74880e\" data-id=\"e74880e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dad916f de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"dad916f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si et preguntes on has d\u2019estudiar FP, la resposta ha de ser\u00a0<strong><em>Ramar FP<\/em><\/strong>. Aquest \u00e9s el centre de refer\u00e8ncia per preparar i formar els joves que decideixen fer Formaci\u00f3 Professional. Por tant, el concepte de formaci\u00f3 professional est\u00e0 lligar a Ramar: el nostre projecte pedag\u00f2gic es basa en el proc\u00e9s de millorament continu. \u00c9s per aix\u00f2, pel fet de trobar-nos sempre en creixement constant, que emergeix i sobresurt un projecte que forma professionals amb excel\u00b7lents resultats humans i acad\u00e8mics.<\/p><h2>El que\u00a0 Ramar FP pot fer per tu<\/h2><p>No es tracta del que s\u2019ensenya sin\u00f3 de com s\u2019ensenya. Aquest aspecte diferencia Ramar FP d\u2019altres centres educatius i marca el seu senyal d\u2019identitat al m\u00f3n\u00a0 de l\u2019ensenyament. Les empreses que contracten una persona que ha estudiat i ha obtingut alguna titulaci\u00f3 a Ramar saben que aquest centre treballa amb l\u2019objectiu de formar persones responsables i competents, atenent tamb\u00e9 a les necessitats reals de la societat. Pretenem contribuir al seu progr\u00e9s i al seu desenvolupament, prioritzant valors tan significatius com <strong>la\u00a0llibertat, la toler\u00e0ncia i la solidaritat<\/strong>. Els alumnes que passen per Ramar adquireixen esperit professional i formaci\u00f3 humana. Per aix\u00f2, si estudies amb nosaltres, adquirir\u00e0s valors afegits que et serviran no nom\u00e9s al m\u00f3n del treball sin\u00f3 tamb\u00e9 a la teva vida.<\/p><ul><li><a href=\"https:\/\/www.lavanguardia.com\/economia\/20210308\/6265591\/empleo-tic-crece-sigue-cubrir-todas-ofertas.html\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.lavanguardia.com\/economia\/20210308\/6265591\/empleo-tic-crece-sigue-cubrir-todas-ofertas.html&amp;source=gmail&amp;ust=1625640242823000&amp;usg=AFQjCNGWtFNEwDuOR2so8p3ZkNeZz33uOA\">TIC (Tecnologies de la Informaci\u00f3 i la Comunicaci\u00f3)<\/a>. Ramar FP ha decidit incorporar la tecnologia a les aules\u00a0 i treballar-la igualment amb la formaci\u00f3 a dist\u00e0ncia. Aquest desplegament permet als alumnes beneficiar-se dels avantatges d\u2019estudiar en un centre adaptat a les\u00a0<strong>noves tecnologies<\/strong>. I, a m\u00e9s, els permet tamb\u00e9 incorporar-se al mercat laboral amb un coneixement adequat de les eines vinculades a l\u2019avantguarda tecnol\u00f2gica.<\/li><li>Model d\u2019ensenyament: es basa en una s\u00f2lida\u00a0<a href=\"https:\/\/www.lavanguardia.com\/vida\/20180406\/442257500965\/educacion-humanistica-clave-para-afrontar-mundo-laboral-segun-rector-usal.html\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.lavanguardia.com\/vida\/20180406\/442257500965\/educacion-humanistica-clave-para-afrontar-mundo-laboral-segun-rector-usal.html&amp;source=gmail&amp;ust=1625640242823000&amp;usg=AFQjCNHf7VocLhnGMbxYngi_3XuWXxI_lg\">formaci\u00f3 human\u00edstica<\/a>,\u00a0perqu\u00e8 \u00e9s un dels pilars b\u00e0sics per poder\u00a0 afrontar el m\u00f3n laboral amb \u00e8xit. Aquest tipus de formaci\u00f3 et permetr\u00e0 comprendre el m\u00f3n en qu\u00e8 vius. A m\u00e9s, rebr\u00e0s la formaci\u00f3 cient\u00edfica que et facilitar\u00e0 poder ajudar a transformar-lo. Volem incidir en les teves <strong>compet\u00e8ncies ling\u00fc\u00edstiques,<\/strong> no nom\u00e9s perqu\u00e8\u00a0 interactu\u00efs amb tothom sin\u00f3, sobretot, perqu\u00e8 siguin la base del teu sistema de pensament..\u00a0<\/li><li>Desenvolupament pedag\u00f2gic: es tracta, tal i com hem dit abans, d\u2019un proc\u00e9s de millorament continu. Aquest tipus\u00a0 d\u2018avaluaci\u00f3 contribueix a donar resposta als reptes i a les necessitats dels nostres alumnes. A m\u00e9s, com a comunitat educativa, ens mantenim sempre\u00a0actius<strong> a les xarxes socials i a les comunitats d\u2019aprenentatge\u00a0professional<\/strong> per poder avan\u00e7ar en la reflexi\u00f3 i en la investigaci\u00f3.\u00a0\u00a0<\/li><\/ul><h2>Emocions i valors<\/h2><ul><li>Formaci\u00f3 emocional. Els valors i les emocions formen part de l\u2019educaci\u00f3 que han de rebre els alumnes. Conjugar aquests aspectes els permet cr\u00e9ixer en tots els \u00e0mbits. D\u2019aquesta manera, arribaran a ser persones madures, responsables i amb estabilitat emocional. Aix\u00f2 far\u00e0 possible que el seu rol a la societat estigui marcat per una clara\u00a0<strong>vocaci\u00f3 de comprom\u00eds<\/strong>\u00a0amb el seu m\u00f3n i amb el seu temps. Treballem amb l\u2019objectiu que l\u2019alumne potenci\u00ef la idea de conviv\u00e8ncia i el desenrotllament d\u2019habilitats socials i que adquireixi gradualment una determinada consci\u00e8ncia ambiental.\u00a0<\/li><li>Seguiment personalitzat. Volem que els nostres alumnes siguin conscients del seu proc\u00e9s d\u2019aprenentatge. Per aix\u00f2, creem entorns i ambients que ajudin a la\u00a0<strong>construcci\u00f3 personal<\/strong>\u00a0del coneixement. En aquest sentit, apliquem sistemes d\u2019avaluaci\u00f3 per assolir la millora personal i perqu\u00e8 els alumnes siguin capa\u00e7os d\u2019usar el seu talent per potenciar l\u2019aprenentatge.<\/li><li>Col\u00b7laboraci\u00f3 amb les fam\u00edlies. Treballem conjuntament. Per tant, necessitem que<strong> les fam\u00edlies siguin corresponsables<\/strong>.. Fomentem un ambient de col\u00b7laboraci\u00f3 per assolir que els\u00a0 nostres alumnes se sentin c\u00f2modes i que puguin progressar acad\u00e8micament de la millor manera possible desenrotllant tot el seu potencial.<\/li><li>Diversitat. La diversitat i la difer\u00e8ncia s\u00f3n motors d\u2019enriquiment social i cultural. Quan acaben els seus estudis, els nostres alumnes\u00a0 estan preparats per conviure en un m\u00f3n global diferent i divers. Potenciem\u00a0<strong>el respecte, la toler\u00e0ncia i la conviv\u00e8ncia\u00a0<\/strong>a fi que els nostres alumnes esdevinguin agents actius al desenrotllament d\u2019un m\u00f3n m\u00e9s just.<\/li><\/ul><p>Esperem que aquest esb\u00f3s sobre\u00a0<a href=\"https:\/\/ramarfp.com\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/ramarfp.com\/&amp;source=gmail&amp;ust=1625640242823000&amp;usg=AFQjCNED3SEQefGnU0gQGDsXYGsD-dq2Dw\">Ramar FP<\/a>\u00a0t\u2019hagi servit para con\u00e8ixer la idiosincr\u00e0sia del nostre centre. La nostra filosofia i el nostre principal objectiu \u00e9s que <u>els nostres\u00a0<a href=\"https:\/\/ramarfp.com\/escuela\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/ramarfp.com\/escuela\/%23&amp;source=gmail&amp;ust=1625640242824000&amp;usg=AFQjCNEwCtmAD89TpRiydPsylPYmwkpD1A\">alumnes surtin preparats\u00a0<\/a><\/u>al m\u00f3n real per afrontar tots els reptes professionals amb qu\u00e8 aniran trobant-se. \u00c9s per aix\u00f2 que treballem amb els m\u00e8todes educatius d\u2019avantguarda, comptem amb els millors professors i\u00a0 ens centrem en el creixement personal i professional dels estudiants. Visita la nostra p\u00e0gina web para saber-ne m\u00e9s coses. T\u2019hi esperem!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Si et preguntes on has d\u2019estudiar FP, la resposta ha de ser&nbsp;Ramar FP. Aquest \u00e9s el centre de refer\u00e8ncia per preparar i formar els joves que decideixen fer Formaci\u00f3 Professional. Por tant, el concepte de formaci\u00f3 professional est\u00e0 lligar a Ramar: el nostre projecte pedag\u00f2gic es basa en el proc\u00e9s de millorament continu. \u00c9s per [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-9723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ramar FP: \u25c9\u203f\u25c9 T\u2019ho expliquem tot.<\/title>\n<meta name=\"description\" content=\"RAMAR FP: T\u2019expliquem tot el que has de saber sobre Ramar FP. \u25c9\u203f\u25c9 No t\u2019ho perdis. El teu futur comen\u00e7a amb la teva formaci\u00f3 \u25c9\u203f\u25c9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ramarfp.com\/ca\/ramar-fp\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tot el que has de con\u00e8ixer de RAMAR FP!\" \/>\n<meta property=\"og:description\" content=\"RAMAR FP: T\u2019expliquem tot el que has de saber sobre Ramar FP. \u25c9\u203f\u25c9 No t\u2019ho perdis. El teu futur comen\u00e7a amb la teva formaci\u00f3 \u25c9\u203f\u25c9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ramarfp.com\/ca\/ramar-fp\/\" \/>\n<meta property=\"og:site_name\" content=\"Ramar FP | Formaci\u00f3n Profesional presencial y FP a distancia\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T08:19:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-24T08:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ramarfp.com\/wp-content\/uploads\/2021\/08\/Ramar-FP2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jago\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jago\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/\"},\"author\":{\"name\":\"Jago\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#\\\/schema\\\/person\\\/801a3fa158a096b83c0d79e06da5c600\"},\"headline\":\"Tot el que has de con\u00e8ixer de RAMAR FP!\",\"datePublished\":\"2021-08-24T08:19:10+00:00\",\"dateModified\":\"2021-08-24T08:23:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/\"},\"wordCount\":853,\"publisher\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ramarfp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Ramar-FP2.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/\",\"url\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/\",\"name\":\"Ramar FP: \u25c9\u203f\u25c9 T\u2019ho expliquem tot.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ramarfp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Ramar-FP2.jpg\",\"datePublished\":\"2021-08-24T08:19:10+00:00\",\"dateModified\":\"2021-08-24T08:23:30+00:00\",\"description\":\"RAMAR FP: T\u2019expliquem tot el que has de saber sobre Ramar FP. \u25c9\u203f\u25c9 No t\u2019ho perdis. El teu futur comen\u00e7a amb la teva formaci\u00f3 \u25c9\u203f\u25c9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ramarfp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Ramar-FP2.jpg\",\"contentUrl\":\"https:\\\/\\\/ramarfp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Ramar-FP2.jpg\",\"width\":1200,\"height\":400,\"caption\":\"Ramar-FP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/ramar-fp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ramar FP\",\"item\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tot el que has de con\u00e8ixer de RAMAR FP!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/\",\"name\":\"Ramar FP | Formaci\u00f3n Profesional presencial y FP a distancia\",\"description\":\"\u27bd Centro Oficial Ramar FP \u27bd Presencial y a distancia \u27bd Facilidades de pago \u27bd Examinamos en toda Espa\u00f1a \u260e \u00a1Asegura tu futuro!\",\"publisher\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#organization\",\"name\":\"Ramar FP Online\",\"url\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ramarfp.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Logoonlinetransparent.png\",\"contentUrl\":\"https:\\\/\\\/ramarfp.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Logoonlinetransparent.png\",\"width\":1704,\"height\":1052,\"caption\":\"Ramar FP Online\"},\"image\":{\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ramarfp.com\\\/ca\\\/#\\\/schema\\\/person\\\/801a3fa158a096b83c0d79e06da5c600\",\"name\":\"Jago\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7391d5e6115e5f475140f8ce495e9dc02feecaf0f5a32b3babbe0305366ed9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7391d5e6115e5f475140f8ce495e9dc02feecaf0f5a32b3babbe0305366ed9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e7391d5e6115e5f475140f8ce495e9dc02feecaf0f5a32b3babbe0305366ed9?s=96&d=mm&r=g\",\"caption\":\"Jago\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ramar FP: \u25c9\u203f\u25c9 T\u2019ho expliquem tot.","description":"RAMAR FP: T\u2019expliquem tot el que has de saber sobre Ramar FP. \u25c9\u203f\u25c9 No t\u2019ho perdis. El teu futur comen\u00e7a amb la teva formaci\u00f3 \u25c9\u203f\u25c9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ramarfp.com\/ca\/ramar-fp\/","og_locale":"ca_ES","og_type":"article","og_title":"Tot el que has de con\u00e8ixer de RAMAR FP!","og_description":"RAMAR FP: T\u2019expliquem tot el que has de saber sobre Ramar FP. \u25c9\u203f\u25c9 No t\u2019ho perdis. El teu futur comen\u00e7a amb la teva formaci\u00f3 \u25c9\u203f\u25c9","og_url":"https:\/\/ramarfp.com\/ca\/ramar-fp\/","og_site_name":"Ramar FP | Formaci\u00f3n Profesional presencial y FP a distancia","article_published_time":"2021-08-24T08:19:10+00:00","article_modified_time":"2021-08-24T08:23:30+00:00","og_image":[{"width":1200,"height":400,"url":"https:\/\/ramarfp.com\/wp-content\/uploads\/2021\/08\/Ramar-FP2.jpg","type":"image\/jpeg"}],"author":"Jago","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Jago","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#article","isPartOf":{"@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/"},"author":{"name":"Jago","@id":"https:\/\/ramarfp.com\/ca\/#\/schema\/person\/801a3fa158a096b83c0d79e06da5c600"},"headline":"Tot el que has de con\u00e8ixer de RAMAR FP!","datePublished":"2021-08-24T08:19:10+00:00","dateModified":"2021-08-24T08:23:30+00:00","mainEntityOfPage":{"@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/"},"wordCount":853,"publisher":{"@id":"https:\/\/ramarfp.com\/ca\/#organization"},"image":{"@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#primaryimage"},"thumbnailUrl":"https:\/\/ramarfp.com\/wp-content\/uploads\/2021\/08\/Ramar-FP2.jpg","articleSection":["Not\u00edcies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/","url":"https:\/\/ramarfp.com\/ca\/ramar-fp\/","name":"Ramar FP: \u25c9\u203f\u25c9 T\u2019ho expliquem tot.","isPartOf":{"@id":"https:\/\/ramarfp.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#primaryimage"},"image":{"@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#primaryimage"},"thumbnailUrl":"https:\/\/ramarfp.com\/wp-content\/uploads\/2021\/08\/Ramar-FP2.jpg","datePublished":"2021-08-24T08:19:10+00:00","dateModified":"2021-08-24T08:23:30+00:00","description":"RAMAR FP: T\u2019expliquem tot el que has de saber sobre Ramar FP. \u25c9\u203f\u25c9 No t\u2019ho perdis. El teu futur comen\u00e7a amb la teva formaci\u00f3 \u25c9\u203f\u25c9","breadcrumb":{"@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ramarfp.com\/ca\/ramar-fp\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#primaryimage","url":"https:\/\/ramarfp.com\/wp-content\/uploads\/2021\/08\/Ramar-FP2.jpg","contentUrl":"https:\/\/ramarfp.com\/wp-content\/uploads\/2021\/08\/Ramar-FP2.jpg","width":1200,"height":400,"caption":"Ramar-FP"},{"@type":"BreadcrumbList","@id":"https:\/\/ramarfp.com\/ca\/ramar-fp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ramar FP","item":"https:\/\/ramarfp.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Tot el que has de con\u00e8ixer de RAMAR FP!"}]},{"@type":"WebSite","@id":"https:\/\/ramarfp.com\/ca\/#website","url":"https:\/\/ramarfp.com\/ca\/","name":"Ramar FP | Formaci\u00f3n Profesional presencial y FP a distancia","description":"\u27bd Centro Oficial Ramar FP \u27bd Presencial y a distancia \u27bd Facilidades de pago \u27bd Examinamos en toda Espa\u00f1a \u260e \u00a1Asegura tu futuro!","publisher":{"@id":"https:\/\/ramarfp.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ramarfp.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/ramarfp.com\/ca\/#organization","name":"Ramar FP Online","url":"https:\/\/ramarfp.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/ramarfp.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/ramarfp.com\/wp-content\/uploads\/2020\/12\/Logoonlinetransparent.png","contentUrl":"https:\/\/ramarfp.com\/wp-content\/uploads\/2020\/12\/Logoonlinetransparent.png","width":1704,"height":1052,"caption":"Ramar FP Online"},"image":{"@id":"https:\/\/ramarfp.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ramarfp.com\/ca\/#\/schema\/person\/801a3fa158a096b83c0d79e06da5c600","name":"Jago","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/4e7391d5e6115e5f475140f8ce495e9dc02feecaf0f5a32b3babbe0305366ed9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e7391d5e6115e5f475140f8ce495e9dc02feecaf0f5a32b3babbe0305366ed9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e7391d5e6115e5f475140f8ce495e9dc02feecaf0f5a32b3babbe0305366ed9?s=96&d=mm&r=g","caption":"Jago"}}]}},"_links":{"self":[{"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/posts\/9723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/comments?post=9723"}],"version-history":[{"count":0,"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/posts\/9723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/media\/9731"}],"wp:attachment":[{"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/media?parent=9723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/categories?post=9723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ramarfp.com\/ca\/wp-json\/wp\/v2\/tags?post=9723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}